{"id":43631,"date":"2024-11-17T15:07:13","date_gmt":"2024-11-17T15:07:13","guid":{"rendered":"https:\/\/nuclearelectrica.ro\/ir\/?page_id=43631"},"modified":"2026-03-19T13:43:33","modified_gmt":"2026-03-19T13:43:33","slug":"advisory-committees","status":"publish","type":"page","link":"https:\/\/nuclearelectrica.ro\/ir\/en\/corporate-governance\/advisory-committees\/","title":{"rendered":"Advisory Committee"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"43631\" class=\"elementor elementor-43631\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e800921 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e800921\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf30cad top column-style-top\" data-id=\"cf30cad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f830dfb elementor-widget elementor-widget-image\" data-id=\"f830dfb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"284\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011.jpg\" class=\"attachment-full size-full wp-image-13555\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011.jpg 1920w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-1024x151.jpg 1024w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-768x114.jpg 768w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-600x89.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c3214b relative elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c3214b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e6981e elementor-container top column-style-top\" data-id=\"3e6981e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab26762 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ab26762\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Advisory committees\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e322c37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e322c37\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b01e3bd top column-style-top\" data-id=\"b01e3bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6018d8 elementor-widget elementor-widget-text-editor\" data-id=\"f6018d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Nomination and Remuneration Committee<\/strong>\u00a0<\/p><ul><li>Gheorghe Ionita &#8211; President<\/li><li>Laurentiu Nicolae Cazan<\/li><li>Vasilica Grajdan<\/li><\/ul><p><strong>2.\u00a0 Audit Committee<\/strong><\/p><ul><li>Andrei Gabriel Benghea Malaies &#8211; President<\/li><li>Vasilica Grajdan<\/li><li>Nina Popa<\/li><\/ul><p><strong>3. Advisory Committee on Nuclear Safety<\/strong><\/p><ul><li>Gheorghe Ionita &#8211; President<\/li><li>Dumitru Chirlesan<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-732fe7f top column-style-top\" data-id=\"732fe7f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d480ad elementor-widget elementor-widget-text-editor\" data-id=\"0d480ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>4.\u00a0 Committee for strategy, development and large investment projects<\/strong>\u00a0<\/p><ul><li>Gheorghe Ionita<\/li><li>Laurentiu Nicolae Cazan<\/li><\/ul><p><b>5. Risk Management Advisory Committee<\/b><\/p><ul><li>Laurentiu Nicolae Cazan &#8211; President<\/li><li>Andrei Gabriel Benghea Malaies<\/li><\/ul><p><strong>6. ESG Advisory Committee<\/strong><\/p><ul><li>Vasilica Grajdan &#8211; President<\/li><li>Dumitru Chirlesan<\/li><li>Nina Popa<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f8fee9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f8fee9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ecd02f top column-style-top\" data-id=\"9ecd02f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5162792 elementor-widget elementor-widget-gva-teams\" data-id=\"5162792\" data-element_type=\"widget\" data-widget_type=\"gva-teams.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-teams gva-element\">  \r\n  <div class=\"gva-teams-grid clearfix grid-ixe8\">\r\n      <div class=\"gva-content-items\"> \r\n        <div class=\"lg-block-grid-3 md-block-grid-3 sm-block-grid-2 xs-block-grid-1 xx-block-grid-1\">\r\n          <div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/dumitru-chirlesan-2\/\"><\/a>\n         <div class=\"test\">\n            <img decoding=\"async\" width=\"1400\" height=\"1106\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/Dumitru-CHIRLESAN-1400x1106-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/Dumitru-CHIRLESAN-1400x1106-1.jpg 1400w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/Dumitru-CHIRLESAN-1400x1106-1-1024x809.jpg 1024w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/Dumitru-CHIRLESAN-1400x1106-1-768x607.jpg 768w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/Dumitru-CHIRLESAN-1400x1106-1-600x474.jpg 600w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/dumitru-chirlesan-2\/\">Dumitru Chirlesan<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Member of the Board of Directors               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div><div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/gheorghe-ionita-2\/\"><\/a>\n         <div class=\"test\">\n            <img decoding=\"async\" width=\"1977\" height=\"2372\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/02\/DSC_8675-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/02\/DSC_8675-1.jpg 1977w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/02\/DSC_8675-1-853x1024.jpg 853w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/02\/DSC_8675-1-768x921.jpg 768w\" sizes=\"(max-width: 1977px) 100vw, 1977px\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/gheorghe-ionita-2\/\">Gheorghe Ionita<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Member of the Board of Directors               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div><div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/vasilica-grajdan-2\/\"><\/a>\n         <div class=\"test\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"825\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/WhatsApp-Image-2022-09-29-at-17.26.06.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/vasilica-grajdan-2\/\">Vasilica Grajdan<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Member of the Board of Directors\r\n               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div><div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/nina-popa\/\"><\/a>\n         <div class=\"test\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1419\" height=\"1600\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/IMG-20251126-WA0015.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/IMG-20251126-WA0015.jpg 1419w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/IMG-20251126-WA0015-908x1024.jpg 908w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/IMG-20251126-WA0015-768x866.jpg 768w\" sizes=\"(max-width: 1419px) 100vw, 1419px\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/nina-popa\/\">Nina Popa<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Member of the Board of Directors\r\n               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div><div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/andrei-gabriel-benghea-malaies-2\/\"><\/a>\n         <div class=\"test\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"405\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/IMG-20251127-WA0000.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/IMG-20251127-WA0000.jpg 405w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/IMG-20251127-WA0000-180x180.jpg 180w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/andrei-gabriel-benghea-malaies-2\/\">Andrei Gabriel Benghea Malaies<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Member of the Board of Directors               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div><div class=\"item-columns\"><div class=\"team-block team-v1\">\n         <div class=\"team-image\">\n         <a class=\"overlay\" href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/laurentiu-nicolae-cazan-2\/\"><\/a>\n         <div class=\"test\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/Laurentiu-Cazan-portrait-1-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/Laurentiu-Cazan-portrait-1-1-scaled.jpg 1706w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/Laurentiu-Cazan-portrait-1-1-682x1024.jpg 682w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/05\/Laurentiu-Cazan-portrait-1-1-768x1152.jpg 768w\" sizes=\"(max-width: 1706px) 100vw, 1706px\" \/>         <\/div>\n\n      <\/div>\n      <div class=\"team-content\">\n      <div class=\"team-content-inner\">\n         <h3 class=\"team-name\"><a href=\"https:\/\/nuclearelectrica.ro\/ir\/en\/team\/laurentiu-nicolae-cazan-2\/\">Laurentiu Nicolae Cazan<\/a><\/h3>\n                     <div class=\"team-job\">\n               <ul style=\"list-style:none;margin-left:-17px;line-height:normal\">\n                  Chairman  of the Board of Directors               <\/ul>\n            <\/div>\n                              <div class=\"socials-team\">\n                                                            <\/div>\n         \n      <\/div>\n   <\/div>\n   <\/div><\/div>        <\/div>\r\n      <\/div>\r\n        <\/div>\r\n  <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Advisory committees 1. Nomination and Remuneration Committee\u00a0 Gheorghe Ionita &#8211; President Laurentiu Nicolae Cazan Vasilica Grajdan 2.\u00a0 Audit Committee Andrei Gabriel Benghea Malaies &#8211; President Vasilica Grajdan Nina Popa 3. Advisory Committee on Nuclear Safety Gheorghe Ionita &#8211; President Dumitru Chirlesan 4.\u00a0 Committee for strategy, development and large investment projects\u00a0 Gheorghe Ionita Laurentiu Nicolae Cazan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":43623,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-43631","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/comments?post=43631"}],"version-history":[{"count":48,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43631\/revisions"}],"predecessor-version":[{"id":49328,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43631\/revisions\/49328"}],"up":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43623"}],"wp:attachment":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/media?parent=43631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}