{"id":43643,"date":"2024-11-17T15:10:10","date_gmt":"2024-11-17T15:10:10","guid":{"rendered":"https:\/\/nuclearelectrica.ro\/ir\/?page_id=43643"},"modified":"2025-12-05T12:40:40","modified_gmt":"2025-12-05T12:40:40","slug":"selection-procedure","status":"publish","type":"page","link":"https:\/\/nuclearelectrica.ro\/ir\/en\/corporate-governance\/selection-procedure\/","title":{"rendered":"Selection procedure"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"43643\" class=\"elementor elementor-43643\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e800921 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e800921\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf30cad top column-style-top\" data-id=\"cf30cad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f830dfb elementor-widget elementor-widget-image\" data-id=\"f830dfb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"284\" src=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011.jpg\" class=\"attachment-full size-full wp-image-13555\" alt=\"\" srcset=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011.jpg 1920w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-1024x151.jpg 1024w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-768x114.jpg 768w, https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2024\/10\/SNN_ptSITE_pagini-SNN_DESPRE-NOI_benzi_02-Guvernanta_20241011-600x89.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c3214b relative elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c3214b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e6981e elementor-container top column-style-top\" data-id=\"3e6981e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab26762 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ab26762\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Selection procedure<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e322c37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e322c37\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5c2b70 top column-style-top\" data-id=\"c5c2b70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-384ae4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"384ae4f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5669315 top column-style-top\" data-id=\"5669315\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cd81e9 elementor-widget elementor-widget-gva-tabs-content\" data-id=\"1cd81e9\" data-element_type=\"widget\" data-widget_type=\"gva-tabs-content.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"gsc-tabs-content\" role=\"tablist\">\n\t\t\t<div class=\"tabs_wrapper\">\n\t\t\t\t\n\t\t\t\t<ul class=\"nav nav_tabs clearfix\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-10acf21\">\n\t\t\t\t\t\t\t<a class=\"active show\" data-toggle=\"tab\" href=\"#8yqn-0\">\n\t\t\t\t\t\t\t\t<span>Selection procedure for the SNN board of directors<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\n\n\t\t\t\t<div class=\"tab-content clearfix\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab-pane fade in active show\" role=\"tabpanel\" id=\"8yqn-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab-content-item no_image\">\n\t\t\t\t\t\t\t\t<p><b><strong>(2025) \u2013 Procedure for selecting candidates for vacant positions on the Board of Directors of Societatea Na\u021bional\u0103 Nuclearelectrica S.A.<\/strong><\/b><\/p><p><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Componenta-Integrala-SNN-en-GB.pdf\">July 30, 2025 \u2013 Selection announcement<\/a><\/p><ul><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F1-SNN-1-en-GB.docx\">Form 1 \u2013 editable<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F2-SNN-1-en-GB.docx\">Form 2 \u2013 editable<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F3-SNN-1-en-GB.docx\">Form 3 \u2013 editable<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F4-SNN-1-en-GB.docx\">Form 4 \u2013 editable<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F5-SNN-1-en-GB.docx\">Form 5 \u2013 editable<\/a><\/li><\/ul><p><b>July 24, 2025 <\/b>\u2013<a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Componenta-Integrala-SNN-en-GB-1.pdf\">Integral component of the Selection Plan for the positions of directors of Societatea Na\u021bional\u0103 Nuclearelectrica S.A.<\/a><\/p><ul><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Profilul-consiliului-en-GB.pdf\">Profile of the Council<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Profil-candidat-en-GB.pdf\">Profile of the Candidate<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Anunt-selectie-en-GB.pdf\">Selection announcements for print and online media<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F1-SNN-2-en-GB.docx\">Form F1<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F2-SNN-1-en-GB-1.docx\">Form F2<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F3-SNN-en-GB.docx\">Form F3<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F4-SNN-en-GB.docx\">Form F4<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Formular-F5-SNN-en-GB.docx\">Form F5<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Proiect-Contract-de-mandat-en-GB.pdf\">Draft mandate contract<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Componenta-initiala-a-planului-de-selectie-2-en-GB.pdf\">Initial component of the selection plan<\/a><\/li><li><a href=\"https:\/\/nuclearelectrica.ro\/ir\/wp-content\/uploads\/sites\/3\/2025\/12\/Scrisoarea-de-asteptari-2-en-GB.pdf\">Letter of expectations<\/a><\/li><\/ul>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Selection procedure Selection procedure for the SNN board of directors (2025) \u2013 Procedure for selecting candidates for vacant positions on the Board of Directors of Societatea Na\u021bional\u0103 Nuclearelectrica S.A. July 30, 2025 \u2013 Selection announcement Form 1 \u2013 editable Form 2 \u2013 editable Form 3 \u2013 editable Form 4 \u2013 editable Form 5 \u2013 editable [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":43623,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-43643","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/comments?post=43643"}],"version-history":[{"count":14,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43643\/revisions"}],"predecessor-version":[{"id":48598,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43643\/revisions\/48598"}],"up":[{"embeddable":true,"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/pages\/43623"}],"wp:attachment":[{"href":"https:\/\/nuclearelectrica.ro\/ir\/wp-json\/wp\/v2\/media?parent=43643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}